{"id":30934,"date":"2019-06-04T14:55:32","date_gmt":"2019-06-04T12:55:32","guid":{"rendered":"http:\/\/136.144.181.85\/~nedzink\/infos-conseils\/systemes-de-facades\/systeme-a-tasseaux\/"},"modified":"2019-06-04T14:55:32","modified_gmt":"2019-06-04T12:55:32","slug":"systeme-a-tasseaux","status":"publish","type":"page","link":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/","title":{"rendered":"Syst\u00e8me \u00e0 tasseaux"},"content":{"rendered":"<h2>\n\tMise en oeuvre en toiture et en fa&ccedil;ade<\/h2>\n<p>\n\tLe syst&egrave;me &agrave; tasseaux convient pour les grandes et petites toitures pr&eacute;sentant une inclinaison min. de 3&deg; (de pr&eacute;f&eacute;rence sup&eacute;rieure &agrave; 7&deg;) ainsi que pour les rev&ecirc;tements de fa&ccedil;ade. La couverture &agrave; tasseaux nedZink standard se compose de bacs en zinc relev&eacute;s de chaque c&ocirc;t&eacute; et s&eacute;par&eacute;s par des tasseaux en bois trap&eacute;zo&iuml;daux. Les tasseaux sont recouverts de couvre-joints.<\/p>\n<p>\n\tCela permet d&rsquo;obtenir l&rsquo;aspect caract&eacute;ristique et relativement rustique du toit &agrave; tasseaux. L&rsquo;&eacute;paisseur du zinc-titane utilis&eacute;<br \/>\n\td&eacute;pend de la largeur des bacs et de la hauteur du toit (voir tableau 6.1.).<\/p>\n<div style=\"float:left;width:230px;padding:0 8px;border:1px solid #888;margin-right:10px;\">\n<p>\n\t\t<strong>Sp&eacute;cification des profils standard de couverture &agrave; tasseaux<\/strong><\/p>\n<p>\n\t\t<strong>Bac standard <\/strong>(fig. 6.1)<br \/>\n\t\tLargeur: au maximum 890 mm, avec relev&eacute; de 55 mm.<br \/>\n\t\tLargeur d&eacute;velopp&eacute;e max. 1000 mm.<br \/>\n\t\t&Eacute;paisseur du mat&eacute;riau: 0,80 mm ou 1,00 mm.<\/p>\n<p>\n\t\t<strong>Couvre-joint standard<\/strong> (fig. 6.2)<br \/>\n\t\tSection: 65 mm x 25 mm<br \/>\n\t\t&Eacute;paisseur du mat&eacute;riau: comme bac standard.<br \/>\n\t\tbavette<br \/>\n\t\tLargeur : 330 mm.<br \/>\n\t\t&Eacute;paisseur du mat&eacute;riau: comme bac standard.<\/p>\n<p>\n\t\t<strong>Pattes (fixes et coulissantes)<\/strong> (voir fig.6.3 et 6.4)<br \/>\n\t\tLargeur : 50 mm. Longueur: &gt; 220 mm.<br \/>\n\t\t&Eacute;paisseur du mat&eacute;riau: comme bac standard.<br \/>\n\t\tLes pattes sont fabriqu&eacute;es par le couvreur. La longueur peut d&eacute;passer la mesure donn&eacute;e ; elle sera coup&eacute;e &agrave; la pose. Les pattes fixes permettent de fixer le bac standard tandis que les pattes coulissantes permettent la dilatation longitudinale du bac en zinc.<\/p>\n<p>\n\t\t<strong>Tasseau <\/strong>(fig. 6.4)<br \/>\n\t\tEn bois de bonne qualit&eacute;, minimum classe de qualit&eacute; C conforme &agrave; nen 5466 (KVh 2000). Le tasseau doit &ecirc;tre bien droit et pr&eacute;cis.<\/p>\n<\/div>\n<h3>\n\tLa couverture &agrave; tasseaux<\/h3>\n<p>\n\tUn toit &agrave; tasseaux est une couverture constitu&eacute;e de plaques de zinc pr&eacute;sentant dans leur longueur des bords relev&eacute;s droits.<\/p>\n<p>\n\tDes tasseaux sont pos&eacute;s entre les bacs sur le voligeage. Ces lattes pr&eacute;sentent une section trap&eacute;zo&iuml;dale et une largeur de 40-50 mm pour une hauteur de 60-70 mm. La finition &eacute;tanche entre les bacs standard et les tasseaux est obtenue par une moulure de couverture (couvre-joint).<\/p>\n<p>\n\tLes toitures &agrave; tasseau sont pos&eacute;es sur le voligeage &agrave; l&rsquo;aide de pattes. La largeur minimum des pattes est de 50 mm; leur &eacute;paisseur minimum est de 0,65 mm. Les pattes sont fix&eacute;es sur ou sous le tasseau en fonction du syst&egrave;me de pose choisi. On travaille &eacute;galement avec des pattes fixes et coulissantes dans le cas des couvertures &agrave; tasseaux. ces pattes sont fix&eacute;es aux m&ecirc;mes endroits que pour une toiture &agrave; joint debout.<\/p>\n<h3>\n\tDilatation<\/h3>\n<p>\n\tEn raison de la dilatation et de la contraction induites par les fluctuations de temp&eacute;rature, les longueurs des bacs ne peuvent pas d&eacute;passer 10 m. Si la longueur de toiture d&eacute;passe 10 m, un joint de dilatation doit &ecirc;tre pr&eacute;vu au niveau des soudures transversales. Son ex&eacute;cution d&eacute;pend de l&rsquo;inclinaison du toit (voir figure 6,7). Le recouvrement est n&eacute;cessaire pour assurer l&rsquo;&eacute;tanch&eacute;it&eacute; de la construction.<\/p>\n<h3>\n\tRev&ecirc;tement de fa&ccedil;ade<\/h3>\n<p>\n\tPour assurer l&rsquo;&eacute;tanch&eacute;it&eacute; &agrave; la pluie de la fa&ccedil;ade, on utilise des bacs sp&eacute;cialement profil&eacute;s avec les tasseaux horizontaux (voir figure 6.5). Lorsque l&rsquo;on utilise des tasseaux pour un rev&ecirc;tement de fa&ccedil;ade vertical, le bord sur&eacute;lev&eacute; du tasseau doit pr&eacute;senter un rebord (voir fig. 6.6)<\/p>\n<p>\n\t<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.nedzink.com\/wp-content\/uploads\/import\/cms\/userfiles\/images\/figures-fr\/p058.png\" style=\"width: 654px; height: 1671px;\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mise en oeuvre en toiture et en fa&ccedil;ade Le syst&egrave;me &agrave; tasseaux convient pour les grandes et petites toitures pr&eacute;sentant une inclinaison min. de 3&deg; (de pr&eacute;f&eacute;rence sup&eacute;rieure &agrave; 7&deg;) ainsi que pour les rev&ecirc;tements de fa&ccedil;ade. La couverture &agrave; tasseaux nedZink standard se compose de bacs en zinc relev&eacute;s de chaque c&ocirc;t&eacute; et s&eacute;par&eacute;s [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":900,"comment_status":"closed","ping_status":"closed","template":"template-import.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-30934","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Syst\u00e8me \u00e0 tasseaux &#8211; NedZink<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syst\u00e8me \u00e0 tasseaux &#8211; NedZink\" \/>\n<meta property=\"og:description\" content=\"Mise en oeuvre en toiture et en fa&ccedil;ade Le syst&egrave;me &agrave; tasseaux convient pour les grandes et petites toitures pr&eacute;sentant une inclinaison min. de 3&deg; (de pr&eacute;f&eacute;rence sup&eacute;rieure &agrave; 7&deg;) ainsi que pour les rev&ecirc;tements de fa&ccedil;ade. La couverture &agrave; tasseaux nedZink standard se compose de bacs en zinc relev&eacute;s de chaque c&ocirc;t&eacute; et s&eacute;par&eacute;s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/\" \/>\n<meta property=\"og:site_name\" content=\"NedZink\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nedzink.com\/wp-content\/uploads\/import\/cms\/userfiles\/images\/figures-fr\/p058.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/systeme-a-tasseaux\\\/\",\"url\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/systeme-a-tasseaux\\\/\",\"name\":\"Syst\u00e8me \u00e0 tasseaux &#8211; NedZink\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/systeme-a-tasseaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/systeme-a-tasseaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nedzink.com\\\/wp-content\\\/uploads\\\/import\\\/cms\\\/userfiles\\\/images\\\/figures-fr\\\/p058.png\",\"datePublished\":\"2019-06-04T12:55:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/systeme-a-tasseaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/systeme-a-tasseaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/systeme-a-tasseaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nedzink.com\\\/wp-content\\\/uploads\\\/import\\\/cms\\\/userfiles\\\/images\\\/figures-fr\\\/p058.png\",\"contentUrl\":\"https:\\\/\\\/www.nedzink.com\\\/wp-content\\\/uploads\\\/import\\\/cms\\\/userfiles\\\/images\\\/figures-fr\\\/p058.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/systeme-a-tasseaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Syst\u00e8me \u00e0 tasseaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/\",\"name\":\"NedZink\",\"description\":\"Zink fabrikant\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/#organization\",\"name\":\"NedZink\",\"url\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nedzink.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo-nedzink_fc_zk.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nedzink.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo-nedzink_fc_zk.jpg\",\"width\":2160,\"height\":688,\"caption\":\"NedZink\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nedzink.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Syst\u00e8me \u00e0 tasseaux &#8211; NedZink","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Syst\u00e8me \u00e0 tasseaux &#8211; NedZink","og_description":"Mise en oeuvre en toiture et en fa&ccedil;ade Le syst&egrave;me &agrave; tasseaux convient pour les grandes et petites toitures pr&eacute;sentant une inclinaison min. de 3&deg; (de pr&eacute;f&eacute;rence sup&eacute;rieure &agrave; 7&deg;) ainsi que pour les rev&ecirc;tements de fa&ccedil;ade. La couverture &agrave; tasseaux nedZink standard se compose de bacs en zinc relev&eacute;s de chaque c&ocirc;t&eacute; et s&eacute;par&eacute;s [&hellip;]","og_url":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/","og_site_name":"NedZink","og_image":[{"url":"https:\/\/www.nedzink.com\/wp-content\/uploads\/import\/cms\/userfiles\/images\/figures-fr\/p058.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/","url":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/","name":"Syst\u00e8me \u00e0 tasseaux &#8211; NedZink","isPartOf":{"@id":"https:\/\/www.nedzink.com\/fr-be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/#primaryimage"},"image":{"@id":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nedzink.com\/wp-content\/uploads\/import\/cms\/userfiles\/images\/figures-fr\/p058.png","datePublished":"2019-06-04T12:55:32+00:00","breadcrumb":{"@id":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/#primaryimage","url":"https:\/\/www.nedzink.com\/wp-content\/uploads\/import\/cms\/userfiles\/images\/figures-fr\/p058.png","contentUrl":"https:\/\/www.nedzink.com\/wp-content\/uploads\/import\/cms\/userfiles\/images\/figures-fr\/p058.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nedzink.com\/fr-be\/systeme-a-tasseaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nedzink.com\/fr-be\/"},{"@type":"ListItem","position":2,"name":"Syst\u00e8me \u00e0 tasseaux"}]},{"@type":"WebSite","@id":"https:\/\/www.nedzink.com\/fr-be\/#website","url":"https:\/\/www.nedzink.com\/fr-be\/","name":"NedZink","description":"Zink fabrikant","publisher":{"@id":"https:\/\/www.nedzink.com\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nedzink.com\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.nedzink.com\/fr-be\/#organization","name":"NedZink","url":"https:\/\/www.nedzink.com\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.nedzink.com\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/www.nedzink.com\/wp-content\/uploads\/2019\/08\/logo-nedzink_fc_zk.jpg","contentUrl":"https:\/\/www.nedzink.com\/wp-content\/uploads\/2019\/08\/logo-nedzink_fc_zk.jpg","width":2160,"height":688,"caption":"NedZink"},"image":{"@id":"https:\/\/www.nedzink.com\/fr-be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.nedzink.com\/fr-be\/wp-json\/wp\/v2\/pages\/30934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nedzink.com\/fr-be\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nedzink.com\/fr-be\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nedzink.com\/fr-be\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nedzink.com\/fr-be\/wp-json\/wp\/v2\/comments?post=30934"}],"version-history":[{"count":0,"href":"https:\/\/www.nedzink.com\/fr-be\/wp-json\/wp\/v2\/pages\/30934\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nedzink.com\/fr-be\/wp-json\/wp\/v2\/media?parent=30934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}